{"id":50908,"date":"2021-09-03T15:12:12","date_gmt":"2021-09-03T15:12:12","guid":{"rendered":"https:\/\/www.bobex.be\/fr-be\/fournisseur\/auvray-vision\/"},"modified":"2025-09-30T10:18:22","modified_gmt":"2025-09-30T10:18:22","slug":"auvray-vision","status":"publish","type":"supplier","link":"https:\/\/www.bobex.be\/fr-be\/fournisseurs\/auvray-vision\/","title":{"rendered":"Auvray Energy"},"content":{"rendered":"\n<p>Auvray Energy (anciennement Auvray Vision) est une entreprise sp\u00e9cialis\u00e9e dans les domaines des <strong>\u00e9nergies renouvelables<\/strong>, de l&rsquo;isolation et de la domotique bas\u00e9e dans la province du Hainaut \u00e0 Thuin.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Auvray Energy (Auvray Vision) : une entreprise sp\u00e9cialis\u00e9e dans les \u00e9nergies renouvelables&nbsp;<\/h3>\n\n\n\n<p>Auvray Energy s&rsquo;est fix\u00e9 une mission : transformer votre habitation pour qu&rsquo;elle soit <strong>plus confortable<\/strong> et <strong>moins \u00e9nergivore<\/strong>. Pour cela, son \u00e9quipe de professionnels propose des <strong>solutions durables et innovantes <\/strong>qui s&rsquo;adaptent \u00e0 vos besoins !&nbsp;<\/p>\n\n\n\n<p>Dans une volont\u00e9 de participer \u00e0 la transition \u00e9cologique, Auvray Energy installe chez vous de nombreux dispositifs qui <strong>produisent ou consomment de l&rsquo;\u00e9nergie verte et renouvelable<\/strong>, tels que :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>des <a href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/\" target=\"_blank\" rel=\"noreferrer noopener\">panneaux solaires photovolta\u00efques<\/a> et des <a href=\"https:\/\/www.bobex.be\/fr-be\/batterie-domestique\/\" target=\"_blank\" rel=\"noreferrer noopener\">batteries de stockage domestiques<\/a> pour produire et stocker de l&rsquo;\u00e9nergie solaire,\u00a0<\/li>\n\n\n\n<li>des <a href=\"https:\/\/www.bobex.be\/fr-be\/bornes-de-recharge\/\" target=\"_blank\" rel=\"noreferrer noopener\">bornes de recharge<\/a> \u00e0 domicile pour vos v\u00e9hicules \u00e9lectriques,\u00a0<\/li>\n\n\n\n<li>des <a href=\"https:\/\/www.bobex.be\/fr-be\/pompe-a-chaleur\/\" target=\"_blank\" rel=\"noreferrer noopener\">pompes \u00e0 chaleur<\/a>, pour le chauffage ou la climatisation,\u00a0<\/li>\n\n\n\n<li>des boilers thermodynamiques pour le chauffage de l&rsquo;eau sanitaire.<\/li>\n<\/ul>\n\n\n\n<p>Enfin, Auvray Energy compte \u00e9galement dans ses services divers travaux d&rsquo;\u00e9lectricit\u00e9 pour la mise en conformit\u00e9 des installations \u00e9lectriques g\u00e9n\u00e9rales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Votre expert en isolation et r\u00e9novation<\/h3>\n\n\n\n<p>Quand on parle de <strong>performances \u00e9nerg\u00e9tiques<\/strong> des b\u00e2timents et globalement d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique, il y a <strong>deux grands domaines<\/strong> sur lesquels vous pouvez jouer pour am\u00e9liorer votre habitation : la <strong>m\u00e9thode de production et de consommation d&rsquo;\u00e9nergie<\/strong> (installation de syst\u00e8mes de production d&rsquo;\u00e9nergie, changement des syst\u00e8mes de chauffage&#8230;) et l&rsquo;<strong>isolation g\u00e9n\u00e9rale du b\u00e2timent<\/strong>.&nbsp;<\/p>\n\n\n\n<p>C&rsquo;est pourquoi, \u00e0 c\u00f4t\u00e9 des services d&rsquo;installations que nous venons de citer, Auvray Energy vous accompagne aussi dans <strong>vos projets de r\u00e9novation de fa\u00e7ade et d&rsquo;isolation compl\u00e8te<\/strong> (murs int\u00e9rieurs, sol, toiture&#8230;), le tout avec des <strong>mat\u00e9riaux durables et \u00e0 haute performance<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Une bonne isolation lutte contre les ph\u00e9nom\u00e8nes de d\u00e9perdition de chaleur : vous r\u00e9duirez ainsi votre consommation de chauffage et gagnerez en confort de vie !&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Domotique, s\u00e9curit\u00e9&#8230; Un partenaire complet !<\/h3>\n\n\n\n<p>Enfin, Auvray Energy compl\u00e8te son portefeuille de services avec des <strong>solutions de s\u00e9curit\u00e9<\/strong> (alarmes, cam\u00e9ras, surveillance \u00e0 distance&#8230;) et des <strong>solutions domotiques<\/strong> pour une maison intelligente.&nbsp;<\/p>\n\n\n\n<p>Auvray Energy est une entreprise \u00e0 taille humaine, au service client irr\u00e9prochable, et avec une approche personnalis\u00e9e pour vous accompagner dans votre projet. Avec son offre large et sur-mesure, transformez durablement votre habitation !&nbsp;<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-50908","supplier","type-supplier","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/supplier\/50908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/supplier"}],"about":[{"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/types\/supplier"}],"version-history":[{"count":3,"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/supplier\/50908\/revisions"}],"predecessor-version":[{"id":222312,"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/supplier\/50908\/revisions\/222312"}],"wp:attachment":[{"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/media?parent=50908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}