{"id":70273,"date":"2021-12-06T14:36:11","date_gmt":"2021-12-06T14:36:11","guid":{"rendered":"https:\/\/www.bobex.be\/fr-be\/?post_type=content&#038;p=70273"},"modified":"2025-09-16T11:16:28","modified_gmt":"2025-09-16T11:16:28","slug":"lg-chem-resu","status":"publish","type":"content","link":"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/","title":{"rendered":"Batterie domestique LG CHEM RESU : Prix 2026 et Informations"},"content":{"rendered":"\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Quel_est_le_prix_dune_batterie_domestique_en_Belgique\" >Quel est le prix d\u2019une batterie domestique en Belgique ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Combien_coute_une_batterie_domestique_LG-CHEM_RESU\" >Combien co\u00fbte une batterie domestique LG-CHEM RESU ?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Comparatif_des_differentes_batteries_LG_CHEM_RESU_65_kwh_10_kwh_10h_13_kwh_16h\" >Comparatif des diff\u00e9rentes batteries LG CHEM RESU : 6,5 kwh, 10 kwh, 10h, 13 kwh, 16h<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#De_33_kwh_a_13_kwh_sur_une_tension_a_48v_ou_400v\" >De 3,3 kwh \u00e0 13 kwh sur une tension \u00e0 48v ou 400v<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Quelle_batterie_domestique_LG_choisir\" >Quelle batterie domestique LG choisir ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#A_quoi_sert_le_LG_chem_resu_plus\" >\u00c0 quoi sert le LG chem resu plus ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#LG_et_ses_concurrents\" >LG et ses concurrents<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Est-ce_rentable_dinvestir_dans_une_batterie_LG_CHEM_RESU\" >Est-ce rentable d\u2019investir dans une batterie LG CHEM RESU ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Les_primes_a_Bruxelles\" >Les primes \u00e0 Bruxelles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Les_primes_en_Wallonie\" >Les primes en Wallonie&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Les_primes_en_Flandre\" >Les primes en Flandre<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Ce_quil_faut_savoir_avant_de_se_lancer_dans_lachat_dune_batterie_domestique\" >Ce qu\u2019il faut savoir avant de se lancer dans l\u2019achat d\u2019une batterie domestique<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Quelle_est_la_duree_de_vie_dune_batterie_domestique_LG_CHEM_RESU\" >Quelle est la dur\u00e9e de vie d&rsquo;une batterie domestique LG CHEM RESU ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Les_batteries_LG_CHEM_RESU_la_solution_en_cas_de_blackout\" >Les batteries LG CHEM RESU, la solution en cas de blackout ?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/#Recevez_des_devis_gratuits\" >Recevez des devis gratuits&nbsp;<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quel_est_le_prix_dune_batterie_domestique_en_Belgique\"><\/span>Quel est le prix d\u2019une batterie domestique en Belgique ? <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En Belgique, le prix des <a href=\"https:\/\/www.bobex.be\/fr-be\/batterie-domestique\/\">batteries domestiques <\/a>s\u2019\u00e9tend de <strong>2.000 euros \u00e0 10.000 euros<\/strong>.<\/p>\n\n\n\n<p>La tranche est large, car il existe quatre cat\u00e9gories de batteries domestiques. Par ailleurs, plusieurs crit\u00e8res, comme la pr\u00e9sence d\u2019un <strong>onduleur<\/strong> ou d\u2019un <strong>EMS<\/strong> int\u00e9gr\u00e9, peuvent \u00eatre pris en compte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Combien_coute_une_batterie_domestique_LG-CHEM_RESU\"><\/span>Combien co\u00fbte une batterie domestique LG-CHEM RESU ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Le co\u00fbt d&rsquo;installation d\u2019une batterie domestique propos\u00e9e par LG-CHEM, en Belgique, s\u2019\u00e9tend de <strong>3.590 euros TTC \u00e0 8.399 euros TTC<\/strong>.&nbsp;<\/p>\n\n\n\n<p>La vente des batteries LG-CHEM est aussi disponible par lot. \u00c0 titre indicatif, comptez <strong>11.181,97 euros<\/strong> toutes charges comprises pour un kit comprenant :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1 batterie lithium LG CHEM 6.5kWh<\/li>\n\n\n\n<li>1 batterie lithium LG CHEM 10kWh<\/li>\n\n\n\n<li>1 kit d&rsquo;extension RESU+<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/www.bobex.be\/wp-uploads\/sites\/2\/\/puissance_des_batteries_solaires.jpg\" alt=\"Batteries au lithium dans un garage\" class=\"wp-image-123026\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comparatif_des_differentes_batteries_LG_CHEM_RESU_65_kwh_10_kwh_10h_13_kwh_16h\"><\/span>Comparatif des diff\u00e9rentes batteries LG CHEM RESU : 6,5 kwh, 10 kwh, 10h, 13 kwh, 16h<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Leader du march\u00e9 des batteries bas\u00e9es sur la technologie par <strong>lithium-ion<\/strong>, la filiale sud-cor\u00e9enne LG-CHEM propose plusieurs batteries domestiques \u00e0 la vente.&nbsp;<\/p>\n\n\n\n<p>Ces batteries, <strong>pr\u00eates \u00e0 l\u2019emploi<\/strong>, disposent toutes d\u2019une dur\u00e9e de vie estim\u00e9e par le fabricant \u00e0 25 ans. Elles ne n\u00e9cessitent pas d\u2019entretien.&nbsp;<\/p>\n\n\n\n<p>Toutes bas\u00e9es sur une technologie utilisant le lithium qui \u00e9vite de subir l&rsquo;effet de m\u00e9moire de charge, leurs diff\u00e9rences de tarifs s\u2019expliquent surtout par leur capacit\u00e9 de stockage, de puissance de sortie et le taux de profondeur de d\u00e9charge.<\/p>\n\n\n\n<p>Nous avons r\u00e9alis\u00e9 un tableau r\u00e9capitulatif des mod\u00e8les les plus vendus afin que vous puissiez les comparer par vous-m\u00eame.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><\/td><th>LG CHEM RESU 6,5 kWh<\/th><th>LG CHEM RESU 10 kWh<\/th><th>LG CHEM RESU 10 h<\/th><th>LG CHEM RESU 13 kWh<\/th><th>LG CHEM RESU 16 h<\/th><\/tr><tr><td>Prix TTC<\/td><td>3.590 \u20ac<\/td><td>5.179 \u20ac<\/td><td>5.599 \u20ac<\/td><td>6.299 \u20ac<\/td><td>8.399 \u20ac<\/td><\/tr><tr><td>Capacit\u00e9 de stockage<\/td><td>6 500 Wh<\/td><td>9 800 Wh<\/td><td>9 600 Wh<\/td><td>13 100 Wh<\/td><td>16 000 Wh<\/td><\/tr><tr><td>Puissance de sortie<\/td><td>4 200 W<\/td><td>5 000W<\/td><td>5 000 W<\/td><td>5 000W<\/td><td>7 000W<\/td><\/tr><tr><td>Profondeur de d\u00e9charge<\/td><td>90 %<\/td><td>90 %<\/td><td>100 %<\/td><td>90 %<\/td><td>100 %<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"De_33_kwh_a_13_kwh_sur_une_tension_a_48v_ou_400v\"><\/span>De 3,3 kwh \u00e0 13 kwh sur une tension \u00e0 48v ou 400v<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>LG CHEM propose plusieurs types de batteries domestiques sur le march\u00e9. Elles sont propos\u00e9es dans la s\u00e9rie RESU et ont une capacit\u00e9 de stockage allant de <strong>3,3 kWh \u00e0 13 kWh<\/strong>. La plupart des batteries domestiques LG CHEM RESU utilisent une basse tension de <strong>48 <\/strong>volts. Les autres conviennent \u00e0 la haute tension de 400 volts.<\/p>\n\n\n\n<p>Gr\u00e2ce aux diff\u00e9rents voltages, il est facile de trouver une batterie domestique LG CHEM RESU qui correspond bien \u00e0 votre installation de panneaux solaires.<\/p>\n\n\n\n<p>Les batteries domestiques LG n&rsquo;ont pas d&rsquo;onduleur int\u00e9gr\u00e9. Si vous disposez d\u00e9j\u00e0 d&rsquo;un <strong>onduleur hybride<\/strong> (onduleur intelligent) avec votre syst\u00e8me de panneaux solaires, chaque batterie domestique LG RESU peut \u00eatre connect\u00e9e directement au syst\u00e8me (sans onduleur suppl\u00e9mentaire).<\/p>\n\n\n\n<p>Si vous disposez d&rsquo;un <strong>onduleur normal<\/strong> avec votre syst\u00e8me de panneaux solaires ou si vous n&rsquo;avez pas de panneaux solaires du tout, vous devrez acheter un onduleur suppl\u00e9mentaire pour connecter la batterie domestique au syst\u00e8me \u00e9lectrique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quelle_batterie_domestique_LG_choisir\"><\/span>Quelle batterie domestique LG choisir ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Il est bon d&rsquo;acheter une batterie domestique dont la capacit\u00e9 de stockage correspond plus ou moins \u00e0 la production quotidienne de vos <a href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/\">panneaux solaires<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" width=\"1200\" height=\"628\" src=\"https:\/\/www.bobex.be\/wp-uploads\/sites\/2\/\/batterie-domestique-1.jpg\" alt=\"batterie domestique fix\u00e9e au mur de maison\" class=\"wp-image-170698\"\/><\/figure>\n\n\n\n<p>En outre, la batterie doit \u00eatre capable de stocker suffisamment d&rsquo;\u00e9nergie pour alimenter votre maison pendant une journ\u00e9e enti\u00e8re.<\/p>\n\n\n\n<p>En Belgique, une installation moyenne de panneaux solaires produit environ<strong> 9,6 kWh par jour<\/strong> et une famille moyenne (2 adultes + 1 enfant) consomme \u00e9galement environ 9,6 kWh par jour.<\/p>\n\n\n\n<p>Dans une telle situation<strong>,<\/strong> une batterie domestique<strong> LG RESU de 10 kWh<\/strong> est un bon choix. Si vos panneaux solaires fournissent beaucoup plus d&rsquo;\u00e9nergie ou si votre foyer utilise beaucoup plus d&rsquo;\u00e9nergie, il est possible de connecter deux batteries domestiques LG ensemble.<\/p>\n\n\n\n<p>Par exemple, vous pouvez connecter une batterie domestique<strong> LG CHEM RESU<\/strong> <strong>6.5<\/strong> \u00e0 une <strong>LG CHEM RESU 13<\/strong>, ce qui porte la capacit\u00e9 de stockage \u00e0 <strong>19,5 kWh.<\/strong><\/p>\n\n\n\n<p>L&rsquo;installation de la deuxi\u00e8me batterie ne doit pas n\u00e9cessairement se faire en m\u00eame temps que la premi\u00e8re, mais peut se faire des mois ou des ann\u00e9es plus tard. La connexion n\u00e9cessite un combinateur LG RESU Battery (environ 600 \u20ac).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A_quoi_sert_le_LG_chem_resu_plus\"><\/span>\u00c0 quoi sert le LG chem resu plus ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Le LG Chem RESU Plus est con\u00e7u pour optimiser la flexibilit\u00e9 et la performance de votre syst\u00e8me de stockage d&rsquo;\u00e9nergie domestique. En permettant la <strong>combinaison de plusieurs batteries LG Chem RESU<\/strong>, comme la RESU 3.3, RESU 6.5 et RESU 10 (48V), il vous offre la possibilit\u00e9 d\u2019adapter votre stockage d\u2019\u00e9nergie selon vos besoins sp\u00e9cifiques.<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 cette technologie, vous pouvez <strong>associer jusqu&rsquo;\u00e0 deux batteries<\/strong> pour maximiser l&rsquo;efficacit\u00e9 de votre syst\u00e8me tout en b\u00e9n\u00e9ficiant d&rsquo;une capacit\u00e9 accrue et d&rsquo;une gestion optimis\u00e9e de l&rsquo;\u00e9nergie. Cela permet non seulement de r\u00e9pondre \u00e0 des exigences \u00e9nerg\u00e9tiques vari\u00e9es mais aussi de garantir une performance optimale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"LG_et_ses_concurrents\"><\/span>LG et ses concurrents<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>LG-CHEM propose une large gamme de batteries qui couvrent presque enti\u00e8rement la tranche des tarifs pratiqu\u00e9s sur le march\u00e9.<\/p>\n\n\n\n<p>L&rsquo;offre de la marque constitue un bon interm\u00e9diaire entre TESLA, dont le mod\u00e8le Powerwall qui co\u00fbte <strong>6.945 \u20ac<\/strong>, et la batterie modulaire rudimentaire \u00e0<strong> 1.900 \u20ac<\/strong> de SolarWatt.<\/p>\n\n\n\n<p>Vous souhaitez recevoir les conseils d&rsquo;un expert afin de faire le choix le plus <strong>adapt\u00e9 <\/strong>\u00e0 votre habitation ? Nous vous mettons en contact avec les meilleurs installateurs de votre r\u00e9gion. Remplissez le formulaire et recevez jusqu&rsquo;\u00e0 5 devis gratuits et sans engagement.<\/p>\n\n\n\n                <div class='bobex-cta-block' style='\n            --button-bg-color: #e13c0e;\n            --button-text-color: #ffffff;\n            --banner-bg-color: #aad4e6;\n            --arrow-main-bg-color: #aad4e6;\n            --arrow-secondary-bg-color: #e5f2f7;\n            --banner-title-color: #10375e;\n            --arrow-title-color: #10375e;\n            --banner-text-color: #545454;\n            --arrow-text-color: #545454;         \n            --invert-range: 0deg;\n        '>\n                    <div class='cta-arrow-text d-flex d-lg-none'>\n                        <a class='cta-button-rounded' href='#ppp'>Je demande un devis gratuitement<\/a>\n                    <\/div>\n                    <div class='d-none d-lg-flex flex-no-wrap'>\n                        <div class=\"col-7 cta-arrow-text d-flex text-color\">\n                            <div class=\"m-auto\">\n                                <div class=\"h3\">Vous souhaitez installer une batterie domestique ?<\/div>\n                                <div class='text-color'>Demandez l&rsquo;avis d&rsquo;experts !<\/div>\n                            <\/div>\n                        <\/div>\n                        <div class='cta-arrow-link col-5'>\n                            <a class='cta-button-rounded' href=\"#ppp\">Je demande un devis gratuitement<\/a>\n                        <\/div>\n                    <\/div>\n                <\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Est-ce_rentable_dinvestir_dans_une_batterie_LG_CHEM_RESU\"><\/span>Est-ce rentable d\u2019investir dans une batterie LG CHEM RESU ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Aujourd\u2019hui, une installation de cellules photovolta\u00efques permet d&rsquo;obtenir une autonomie estim\u00e9e \u00e0 <strong>30 %<\/strong> de votre <strong>consommation annuelle<\/strong> en \u00e9lectricit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" width=\"1200\" height=\"628\" src=\"https:\/\/www.bobex.be\/wp-uploads\/sites\/2\/\/batterie-panneaux-1.jpg\" alt=\"Batteries domestique pour panneaux solaires\" class=\"wp-image-170704\"\/><\/figure>\n\n\n\n<p>Investir dans une batterie domestique peut augmenter votre autoconsommation <strong>jusqu\u2019\u00e0 80 %<\/strong>. Le rendement de votre batterie domestique sera donc d\u00e9termin\u00e9 en fonction de sa capacit\u00e9 de stockage, puissance de sortie et la fa\u00e7on dont vous consommez l\u2019\u00e9nergie.<\/p>\n\n\n\n<p>Les Batteries LG CHEM RESU pourraient donc vous permettre d\u2019augmenter votre autoconsommation de <strong>50 \u00e0 60 % <\/strong>gr\u00e2ce \u00e0 leur capacit\u00e9 de stockage et leur puissance de sortie (<strong>qui peut atteindre 100 %<\/strong>).<\/p>\n\n\n\n<p>Un dernier crit\u00e8re doit  \u00eatre pris en compte, il s\u2019agit de la r\u00e9gion dans laquelle vous r\u00e9sidez. En effet, chaque r\u00e9gion dispose de son propre syst\u00e8me de prime, aide et tarif. Les politiques men\u00e9es par les diff\u00e9rentes instances f\u00e9d\u00e9rales ont un impact sur la vitesse \u00e0 laquelle vous allez pouvoir <strong>rentabiliser<\/strong> votre investissement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Les_primes_a_Bruxelles\"><\/span>Les primes \u00e0 Bruxelles<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>La suppression des aides compensatrices et la mise en place du tarif d\u2019injection, le 1er novembre 2021 a eu un impact d\u00e9favorable sur le rendement attendu par les propri\u00e9taires de panneaux photovolta\u00efques bruxellois.<\/p>\n\n\n\n<p>Le <strong>tarif d\u2019injection<\/strong> est mis en place lorsqu\u2019on souhaite encourager les prosumers \u00e0 consommer l\u2019\u00e9nergie qu\u2019ils produisent. Il devient, en effet, plus rentable de consommer sa propre production, plut\u00f4t que de la vendre aux fournisseurs d\u2019\u00e9nergies.&nbsp;<\/p>\n\n\n\n<p>Investir dans une batterie domestique vous permettra de ne plus vendre votre \u00e9lectricit\u00e9<strong> \u00e0 perte<\/strong>. Vous pourrez ainsi consommer votre surplus d\u2019\u00e9nergie renouvelable et augmenter votre autoconsommation.<\/p>\n\n\n\n<p>Cette solution est celle qui permet le meilleur rendement, \u00e0 Bruxelles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Les_primes_en_Wallonie\"><\/span>Les primes en Wallonie&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Si vous r\u00e9sidez en Wallonie, vous d\u00e9pendez du <strong><a href=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/prix\/tarif-prosumer\/\" target=\"_blank\" rel=\"noreferrer noopener\">tarif prosumer<\/a><\/strong>. L\u2019objectif de ce tarif est sensiblement le m\u00eame que pour le tarif prosumer : encourager l\u2019<strong>autoconsommation<\/strong>. Ce tarif est d\u00fb au gouvernement wallon lorsque vous injectez votre surplus d\u2019\u00e9nergie solaire sur le r\u00e9seau de distribution.<\/p>\n\n\n\n<p>M\u00eame si l\u2019\u00e9lectricit\u00e9 introduite sur le r\u00e9seau de distribution est d\u00e9duite de votre facture finale, il s\u2019av\u00e8re <strong>plus rentable<\/strong> de limiter les \u00e9changes avec le r\u00e9seau de distribution classique.<\/p>\n\n\n\n<p>Investir dans une batterie domestique vous permettra de diminuer vos \u00e9changes avec le r\u00e9seau de distribution. Vous pourrez ainsi consommer votre surplus d\u2019\u00e9nergie solaire et augmenter votre consommation.&nbsp;<\/p>\n\n\n\n<p>Cette solution est celle qui permet le meilleur rendement, en Wallonie.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Les_primes_en_Flandre\"><\/span>Les primes en Flandre<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En Flandre, comme \u00e0 Bruxelles, c&rsquo;est le <strong>tarif d\u2019injection<\/strong> qui est en vigueur, depuis octobre 2020. Votre facture est donc proche de votre consommation r\u00e9elle.<\/p>\n\n\n\n<p>Comme \u00e0 Bruxelles, investir dans une batterie domestique vous permettra donc un meilleur rendement.<\/p>\n\n\n\n<p>Par ailleurs, la Flandre a mis en place une prime \u00e0 l\u2019installation de batterie solaire pouvant s\u2019\u00e9lever \u00e0 <strong>2.550 \u20ac<\/strong>, en 2021. La prime sera ensuite <strong>d\u00e9gressive <\/strong>jusqu\u2019en 2024. Elle ne sera alors que de 575 \u20ac.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ce_quil_faut_savoir_avant_de_se_lancer_dans_lachat_dune_batterie_domestique\"><\/span>Ce qu\u2019il faut savoir avant de se lancer dans l\u2019achat d\u2019une batterie domestique<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Une batterie solaire peut-elle vraiment vous permettre d\u2019atteindre la pleine autonomie ? Pendant combien de temps pourrez-vous l\u2019utiliser ? Ces questions font parties de celles qu vous devez vous poser avant d\u2019investir dans une batterie de stockage domestique.<\/p>\n\n\n\n<div class=\"wp-block-bobex-frequently-asked-questions bobex-faq-main-wrapper\">\n            <div class=\"bobex-simple-question-answer-block\">\n                <div class=\"bobex-simple-question-answer-block__question\" style=\"background-color: #63b0d1!important; color: white!important;\">\n                    <h3 style=\"color: white!important; margin:unset; font-size:1.2rem;\" class=\"bobex-simple-question-answer-block__question__content\"><span class=\"ez-toc-section\" id=\"Quelle_est_la_duree_de_vie_dune_batterie_domestique_LG_CHEM_RESU\"><\/span>Quelle est la dur\u00e9e de vie d&rsquo;une batterie domestique LG CHEM RESU ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                    <div class=\"bobex-simple-question-answer-block__question__toggle\">+<\/div>\n                <\/div>\n                <div class=\"bobex-simple-question-answer-block__answer\" style=\"background-color: !important; color: black!important;\">\n                    <div class=\"bobex-simple-question-answer-block__answer__content\">La dur\u00e9e de vie d\u2019une batterie domestique est g\u00e9n\u00e9ralement estim\u00e9e entre <strong>10 et 20 ans<\/strong>.<br>De son c\u00f4t\u00e9, LG CHEM RESU estime la dur\u00e9e de vie de ses batteries au lithium \u00e0 <strong>25 ans<\/strong>. Investir dans une batterie domestique implique donc de penser la rentabilit\u00e9 de celle-ci, sur le long terme.<\/div>\n                    <div>\n<div class=\"wp-block-bobex-simple-question-answer\"><\/div>\n<\/div>\n                <\/div>\n            <\/div>\n        \n\n\n            <div class=\"bobex-simple-question-answer-block\">\n                <div class=\"bobex-simple-question-answer-block__question\" style=\"background-color: #63b0d1!important; color: white!important;\">\n                    <h3 style=\"color: white!important; margin:unset; font-size:1.2rem;\" class=\"bobex-simple-question-answer-block__question__content\"><span class=\"ez-toc-section\" id=\"Les_batteries_LG_CHEM_RESU_la_solution_en_cas_de_blackout\"><\/span>Les batteries LG CHEM RESU, la solution en cas de blackout ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                    <div class=\"bobex-simple-question-answer-block__question__toggle\">+<\/div>\n                <\/div>\n                <div class=\"bobex-simple-question-answer-block__answer\" style=\"background-color: !important; color: black!important;\">\n                    <div class=\"bobex-simple-question-answer-block__answer__content\">De plus en plus de particuliers s\u2019int\u00e9ressent \u00e0 des syst\u00e8mes d\u2019alimentation en \u00e9lectricit\u00e9, ind\u00e9pendants des r\u00e9seaux de distribution, afin d\u2019\u00eatre autonome en cas de coupure de courant ou <strong>panne g\u00e9n\u00e9rale<\/strong>.<br><br>L\u2019engouement g\u00e9n\u00e9ral pour les batteries domestiques est peut-\u00eatre en partie li\u00e9 \u00e0 ce nouvel int\u00e9r\u00eat. Il faut toutefois savoir qu\u2019une batterie domestique ne prend pas le relais en cas de blackout sans <strong>EMS<\/strong> (Energy Management System) int\u00e9gr\u00e9 ou raccord\u00e9.<br><br>Dans le cas d\u2019un dysfonctionnement sur le r\u00e9seau de distribution, les techniciens envoient une puissante d\u00e9charge sur le r\u00e9seau afin de faire disjoncter les appareils qui pourraient provoquer des d\u00e9g\u00e2ts. <strong>Sans EMS<\/strong> votre batterie sera inutilisable apr\u00e8s cette d\u00e9charge.\u00a0<br><br>Gr\u00e2ce \u00e0 l\u2019EMS l\u2019\u00e9nergie que vous produisez est accessible dans n&rsquo;importe quelle situation.<br>LG-CHEM propose des <strong>kits <\/strong>avec des EMS int\u00e9gr\u00e9s. Pr\u00eatez attention \u00e0 cet \u00e9l\u00e9ment, car toutes leurs offres n&rsquo;incluent pas automatiquement ce syst\u00e8me.\u00a0<\/div>\n                    <div>\n<div class=\"wp-block-bobex-simple-question-answer\"><\/div>\n<\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n                    <script type=\"application\/ld+json\">\n                        {\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Quelle est la dur\\u00e9e de vie d'une batterie domestique LG CHEM RESU ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La dur\\u00e9e de vie d\\u2019une batterie domestique est g\\u00e9n\\u00e9ralement estim\\u00e9e entre <strong>10 et 20 ans<\\\/strong>.<br>De son c\\u00f4t\\u00e9, LG CHEM RESU estime la dur\\u00e9e de vie de ses batteries au lithium \\u00e0 <strong>25 ans<\\\/strong>. Investir dans une batterie domestique implique donc de penser la rentabilit\\u00e9 de celle-ci, sur le long terme.\"}},{\"@type\":\"Question\",\"name\":\"Les batteries LG CHEM RESU, la solution en cas de blackout ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"De plus en plus de particuliers s\\u2019int\\u00e9ressent \\u00e0 des syst\\u00e8mes d\\u2019alimentation en \\u00e9lectricit\\u00e9, ind\\u00e9pendants des r\\u00e9seaux de distribution, afin d\\u2019\\u00eatre autonome en cas de coupure de courant ou <strong>panne g\\u00e9n\\u00e9rale<\\\/strong>.<br><br>L\\u2019engouement g\\u00e9n\\u00e9ral pour les batteries domestiques est peut-\\u00eatre en partie li\\u00e9 \\u00e0 ce nouvel int\\u00e9r\\u00eat. Il faut toutefois savoir qu\\u2019une batterie domestique ne prend pas le relais en cas de blackout sans <strong>EMS<\\\/strong> (Energy Management System) int\\u00e9gr\\u00e9 ou raccord\\u00e9.<br><br>Dans le cas d\\u2019un dysfonctionnement sur le r\\u00e9seau de distribution, les techniciens envoient une puissante d\\u00e9charge sur le r\\u00e9seau afin de faire disjoncter les appareils qui pourraient provoquer des d\\u00e9g\\u00e2ts. <strong>Sans EMS<\\\/strong> votre batterie sera inutilisable apr\\u00e8s cette d\\u00e9charge.\\u00a0<br><br>Gr\\u00e2ce \\u00e0 l\\u2019EMS l\\u2019\\u00e9nergie que vous produisez est accessible dans n'importe quelle situation.<br>LG-CHEM propose des <strong>kits <\\\/strong>avec des EMS int\\u00e9gr\\u00e9s. Pr\\u00eatez attention \\u00e0 cet \\u00e9l\\u00e9ment, car toutes leurs offres n'incluent pas automatiquement ce syst\\u00e8me.\\u00a0\"}}]}\n                    <\/script>\n                \n\n\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" width=\"1200\" height=\"628\" src=\"https:\/\/www.bobex.be\/wp-uploads\/sites\/2\/\/eclairage-bougies-1.jpg\" alt=\"femme dans le salon qui \u00e9claire \u00e0 la bougie\" class=\"wp-image-170713\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Recevez_des_devis_gratuits\"><\/span>Recevez des devis gratuits&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Vous r\u00e9fl\u00e9chissez \u00e0 investir dans des batteries solaires et souhaitez faire appel \u00e0 un installateur ? Vous h\u00e9sitez encore ? Sur notre site, vous avez la possibilit\u00e9 de comparer les meilleurs installeurs de votre r\u00e9gion. <\/p>\n\n\n\n<p>Vous souhaitez recevoir des propositions personnalis\u00e9es et adapt\u00e9es \u00e0 votre situation ? Remplissez simplement notre formulaire et recevez jusqu&rsquo;\u00e0<strong> 5 devis<\/strong> gratuits et sans engagement.&nbsp;<\/p>\n\n\n<div id=\"ppp\" class=\"bob-form-wrapper\" data-ajax_url=\"https:\/\/www.bobex.be\/fr-be\/wp-admin\/admin-ajax.php\" data-fa_a=\"\" data-fa_b=\"\"><div class=\"loader\" aria-hidden=\"true\"><\/div>    <div>\n        <div class=\"row mx-auto mb-2\" style=\"max-width: 900px;\">\n            <div class=\"col-md-4\"><i class=\"mr-1 fas fa-check\" style=\"color:green;\"><\/i>Devis gratuits et rapides<\/div>\n            <div class=\"col-md-4\"><i class=\"mr-1 fas fa-check\" style=\"color:green;\"><\/i>Sans engagement et obligation<\/div>\n            <div class=\"col-md-4\"><i class=\"mr-1 fas fa-check\" style=\"color:green;\"><\/i>Professionnels agr\u00e9\u00e9s<\/div>\n        <\/div>\n    <\/div><div id=\"form-6a049267cd988\" class=\"bob-form-container\" style=\"background-color: white; font-family: Roboto, sans-serif !important; font-size: 16px !important; color: #545454; box-shadow: 0 2px 10px rgba(0,0,0,0.1); --font_title: Poppins; --font_size_title: 20px; --title_bg_color: #175da6; --copyright_color: #fde8e1; --box_upload_color: #e5f2f7; padding:unset;\" data-form-type=\"inline\" data-form-id=\"6a049267cd988\"><style>#form-6a049267cd988 .bob-form-inline-question.even {\n  background-color: #e5f2f7;\n}\n#form-6a049267cd988 .single_multiple.multiple_button {\n  background-color: #e5f2f7 !important;\n}\n#form-6a049267cd988 .bob-form-inline-question--hidden {\n  display: none;\n}<\/style><div class=\"form-questions\"><form id=\"bob-form\" class=\"bob-form bob-form-tag\" method=\"post\" action=\"https:\/\/www.bobex.be\/fr-be\/wp-admin\/admin-ajax.php?action=bobex-form-validation\">    <div class=\"form-title\">\n        Formulez votre demande\n        <div class=\"form-title-info-line\">\n            R\u00e9pondez \u00e0 quelques questions et entrez en contact avec des sp\u00e9cialistes fiables. Nous vous demandons vos coordonn\u00e9es afin de s\u00e9lectionner les professionnels actifs dans votre r\u00e9gion.\n        <\/div>\n    <\/div><div class=\"form-questions bob-form-inline-question\"><div class=\"row\"><div class=\"question col-md-4\"><label>1*. Quelle est votre consommation d&rsquo;\u00e9lectricit\u00e9 annuelle (estim\u00e9e)?<\/label><\/div><div class=\"answer col-md-8\"><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-0-1\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio\" value=\"1\"  required=\"required\"><label for=\"6a049267cd988-input-0-1\">Moins de 3.000 kWh (1 personne)<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-0-2\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio\" value=\"2\"  required=\"required\"><label for=\"6a049267cd988-input-0-2\">3.000-4.000 kWh (2-3 personnes)<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-0-3\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio\" value=\"3\"  required=\"required\"><label for=\"6a049267cd988-input-0-3\">4.000-5.000 kWh (3-4 personnes )<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-0-4\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio\" value=\"4\"  required=\"required\"><label for=\"6a049267cd988-input-0-4\">5.000-6.000 kWh (4-5 personnes )<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-0-5\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio\" value=\"5\"  required=\"required\"><label for=\"6a049267cd988-input-0-5\">Plus de 6.000 kWh (piscine, pompe \u00e0 chaleur, &#8230;)<\/label><\/div><\/div><\/div><\/div><div class=\"form-questions bob-form-inline-question even\"><div class=\"row\"><div class=\"question col-md-4\"><label>2*. O\u00f9 voulez-vous installer les panneaux solaires?<\/label><\/div><div class=\"answer col-md-8\"><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-1-1\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio2\" value=\"1\"  required=\"required\"><label for=\"6a049267cd988-input-1-1\">Sur un toit inclin\u00e9<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-1-2\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio2\" value=\"2\"  required=\"required\"><label for=\"6a049267cd988-input-1-2\">Sur un toit plat<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-1-3\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio2\" value=\"3\"  required=\"required\"><label for=\"6a049267cd988-input-1-3\">A un autre endroit (ex.: au sol)<\/label><\/div><\/div><\/div><\/div><div class=\"form-questions bob-form-inline-question\"><div class=\"row\"><div class=\"question col-md-4\"><label>3*. Etes-vous aussi int\u00e9ress\u00e9 par une batterie domestique?<\/label><\/div><div class=\"answer col-md-8\"><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-2-1\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio3\" value=\"1\"  required=\"required\"><label for=\"6a049267cd988-input-2-1\">Oui<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-2-2\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio3\" value=\"2\"  required=\"required\"><label for=\"6a049267cd988-input-2-2\">Non<\/label><\/div><\/div><\/div><\/div><div class=\"form-questions bob-form-inline-question even\"><div class=\"row\"><div class=\"question col-md-4\"><label>4*. Quand d\u00e9sirez-vous faire rendez-vous (n\u00e9cessaire pour les mesures et le devis)?<\/label><\/div><div class=\"answer col-md-8\"><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-3-1\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio4\" value=\"1\"  required=\"required\"><label for=\"6a049267cd988-input-3-1\">Le matin<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-3-2\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio4\" value=\"2\"  required=\"required\"><label for=\"6a049267cd988-input-3-2\">L&rsquo;apr\u00e8s-midi<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-3-3\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio4\" value=\"3\"  required=\"required\"><label for=\"6a049267cd988-input-3-3\">En soir\u00e9e (apr\u00e8s 17h)<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-3-4\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio4\" value=\"4\"  required=\"required\"><label for=\"6a049267cd988-input-3-4\">A un autre moment (\u00e0 convenir)<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-3-5\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio4\" value=\"5\"  required=\"required\"><label for=\"6a049267cd988-input-3-5\">Je ne d\u00e9sire pas de rendez-vous<\/label><\/div><\/div><\/div><\/div><div class=\"form-questions bob-form-inline-question\"><div class=\"row\"><div class=\"question col-md-4\"><label>5*. Pour quel type de b\u00e2timent d\u00e9sirez-vous des panneaux solaires?<\/label><\/div><div class=\"answer col-md-8\"><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-4-1\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio5\" value=\"1\"  required=\"required\"><label for=\"6a049267cd988-input-4-1\">Propri\u00e9t\u00e9 priv\u00e9e<\/label><\/div><div class=\"bob-form-radio d-flex\"><input type=\"radio\" class=\"inline-radio\" id=\"6a049267cd988-input-4-2\" data-unique-id=\"6a049267cd988\" name=\"XML_extra_radio5\" value=\"2\"  required=\"required\"><label for=\"6a049267cd988-input-4-2\">Immeuble commercial ou industriel<\/label><\/div><\/div><\/div><\/div><div class=\"form-questions bob-form-inline-question even\"><div class=\"d-flex flex-column\"><label class=\"question\" for=\"6a049267cd988-input-5\">6. Description de votre projet<\/label><textarea class=\"bob-form-input\" name=\"XML_remarks\" id=\"6a049267cd988-input-5\" data-unique-id=\"6a049267cd988\"><\/textarea><\/div><\/div><div class=\"bob-inline-form bob-form-tag upload-box mb-3\">\n                    <div class=\"row\">\n                        <div class=\"col-md-12 mb-2 question\">Ajouter des photos ou des pi\u00e8ces jointes (en Option)<\/div>\n                        <div class=\"col-md-12\">\n                            <div class=\"box__input\" style=\"background-color: #e5f2f7;\"\n                                 ondrop=\"drop(event)\"\n                                 ondragover=\"allowDrop(event)\"\n                                 ondragleave=\"removeDropFx(event)\"\n                                >\n                                <input type=\"file\"\n                                       class=\"file__input\"\n                                       name=\"attachments[]\"\n                                       id=\"attachments\"\n                                       multiple=\"multiple\"\n                                       accept=\"image\/jpeg, image\/png, image\/gif, application\/pdf\"\n                                       data-multiple-caption=\"{count} files selected\">\n                                <div>\n                                    <label for=\"attachments\"><strong>S\u00e9lectionnez un fichier <\/strong>ou glissez-le ici<\/label>\n                                    <span class=\"box__button bobex-round-cta m-1 py-1\"\n                                          style=\"mix-blend-mode: luminosity\">\n                                        <i class=\"fas fa-cloud-upload-alt text-white\"><\/i>\n                                        T\u00e9l\u00e9charger\n                                    <\/span>\n                                <\/div>\n            \n                                <div class=\"row preview_wrapper m-0\"><\/div>\n                            <\/div>\n            \n                            <div class=\"box__uploading\">Uploading\u2026<\/div>\n                            <div class=\"box__success\">Done!<\/div>\n                            <div class=\"box__error\">Error! <span><\/span>.<\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>    <div class=\"form-title\">\n        Vos donn\u00e9es\n    <\/div><div class=\"bob-form-contact-data\" style=\"padding: 20px\"><div class=\"row lead-info\"><div class=\"col-md-6 mb-3\">  <div class=\"form-group\">    <input value=\"\" type=\"text\" class=\"form-control\" id=\"firstName\" name=\"firstName\" placeholder=\"Pr\u00e9nom\" required>    <div class=\"valid-feedback\">Enchant\u00e9 !<\/div>    <div class=\"invalid-feedback\">Veuillez indiquer votre pr\u00e9nom<\/div>  <\/div><\/div><div class=\"col-md-6 mb-3\">  <div class=\"form-group\">    <input value=\"\" type=\"text\" class=\"form-control\" id=\"lastName\" name=\"lastName\" placeholder=\"Nom\" required>    <div class=\"valid-feedback\">Sympa<\/div>    <div class=\"invalid-feedback\">Veuillez indiquer votre nom de famille<\/div>  <\/div><\/div><div class=\"col-md-12 mb-3\">  <div class=\"form-group\">    <input value=\"\" type=\"email\" class=\"form-control\" id=\"email\" name=\"email\" placeholder=\"E-mail\" required style=\"max-width: unset;\">    <div class=\"valid-feedback\">C&rsquo;est tout bon<\/div>    <div class=\"invalid-feedback\">Veuillez indiquer une adresse e-mail valide<\/div>  <\/div><\/div><div class=\"col-md-12 mb-3\">  <div class=\"form-group\">    <input value=\"\" type=\"tel\" class=\"form-control\" id=\"phone\" name=\"phone\" placeholder=\"T\u00e9l\u00e9phone\" required style=\"max-width: unset;\">    <div class=\"valid-feedback\">Parfait<\/div>    <div class=\"invalid-feedback\">Veuillez indiquer un num\u00e9ro de t\u00e9l\u00e9phone valide<\/div>  <\/div><\/div><div class=\"col-md-12 mb-3\">  <div class=\"form-group\">    <input value=\"\" type=\"text\" class=\"form-control\" id=\"companyAddress\" name=\"companyAddress\" placeholder=\"Adresse\" required style=\"max-width: unset;\">    <div class=\"valid-feedback\">C&rsquo;est not\u00e9<\/div>    <div class=\"invalid-feedback\">Veuillez indiquer une adresse valide<\/div>  <\/div><\/div><div class=\"col-md-6 mb-3\">  <div class=\"form-group\">    <input value=\"\" type=\"text\" class=\"form-control\" id=\"companyPostalCode\" name=\"companyPostalCode\" placeholder=\"Code postal\" required>    <div class=\"valid-feedback\">Excellent !<\/div>    <div class=\"invalid-feedback\">Veuillez indiquer un code postal valide<\/div>  <\/div><\/div><div class=\"col-md-6 mb-3\">  <div class=\"form-group\">    <input value=\"\" type=\"text\" class=\"form-control\" id=\"companyCity\" name=\"companyCity\" placeholder=\"Ville\" required>    <div class=\"valid-feedback\">Bien jou\u00e9<\/div>    <div class=\"invalid-feedback\">Veuillez indiquer une ville valide<\/div>  <\/div><\/div><div class=\"d-flex mt-3\"><input name=\"promoOptin\" value=\"true\" id=\"promoOptin\" type=\"checkbox\" class=\"me-2\" style=\"width: unset\"><label for=\"promoOptin\">Je souhaite rester inform\u00e9 de ma demande et recevoir des conseils pratiques (fortement recommand\u00e9 !) <\/label><\/div><\/div><\/div><input type=\"hidden\" class=\"session_var\" name=\"newform\" value=\"true\"><input type=\"hidden\" class=\"session_var\" name=\"lead-validation-nonce\" value=\"a6b5b7d414\"><input type=\"hidden\" class=\"session_var\" name=\"aff\" value=\"minisite\"><input type=\"hidden\" class=\"session_var\" name=\"utm_source\" value=\"https:\/\/www.bobex.be\/fr-be\/wp-json\/v2\/content\/70273\"><input type=\"hidden\" class=\"session_var\" name=\"bobx\" value=\"\"><input type=\"hidden\" class=\"session_var\" name=\"sessionType\" value=\"B2C\"><input type=\"hidden\" class=\"session_var\" name=\"utm_medium\" value=\"web\"><input type=\"hidden\" class=\"session_var\" name=\"utm_campaign\" value=\"search\"><input type=\"hidden\" class=\"session_var\" name=\"rem_source\" value=\"https:\/\/www.bobex.be\/fr-be\/panneaux-solaires\/batterie-panneau-solaire\/lg-chem-resu\/\"><input type=\"hidden\" class=\"session_var\" name=\"pixel_id\" value=\"-1\"><input type=\"hidden\" class=\"session_var\" name=\"tabo_id\" value=\"-1\"><input type=\"hidden\" class=\"session_var\" name=\"click_id\" value=\"-1\"><input type=\"hidden\" class=\"session_var\" name=\"gclid\" value=\"-1\"><input type=\"hidden\" class=\"session_var\" name=\"msclkid\" value=\"-1\"><input type=\"hidden\" class=\"session_var\" name=\"past_aff\" value=\"bobex\"><input type=\"hidden\" class=\"session_var\" name=\"redirectTo\" value=\"BE\"><input type=\"hidden\" class=\"session_var\" name=\"is_type_id\" value=\"true\"><input type=\"hidden\" class=\"session_var\" name=\"typeid\" value=\"11364\"><input type=\"hidden\" class=\"session_var\" name=\"companyType\" value=\"label.companytype.consumer\"><input type=\"hidden\" class=\"session_var\" name=\"input_names\" value=\"XML_extra_radio,XML_extra_radio2,XML_extra_radio3,XML_extra_radio4,XML_extra_radio5,XML_remarks\"><input type=\"hidden\" class=\"form_context\" value=\"BE\"><img decoding=\"async\" class=\"bobex-pixel\" src=\"\" alt=\"\" style=\"display:none\" \/>    <div class=\"bob-form-submit d-flex justify-content-center\">\n        <button type=\"submit\" class=\"form-submit\" style=\"background-color: #F1653A; color: white; border: none !important; border-radius: 5px !important; font-family: Roboto, sans-serif; font-size: 16px;\">\n            Demander un devis\n        <\/button>\n    <\/div>    <div class=\"bob-inline-form form-footer\" style=\"border-radius: 0 0 10px 10px\">\n        <div class=\"bob-form-privacy-text\">\n            <div style=\"float:left;\"><i class=\"fa fa-lock\"><\/i><\/div>\n            <div class=\"ms-2\">\n                <div style='padding-left: 15px;font-size: 0.8em !important;z-index: 10;'><b>Nous respectons votre vie priv\u00e9e<\/b><br> Conform\u00e9ment \u00e0 la loi du 8\/12\/1992 relative \u00e0 la protection de la vie priv\u00e9e, vous disposez d&rsquo;un droit d&rsquo;acc\u00e8s et de rectification \u00e0 vos donn\u00e9es. Pour en savoir plus, consultez notre <span class=\"link_ob\" data-link=\"aHR0cHM6Ly93d3cuYm9iZXguYmUvZnItYmUvcHJvdGVjdGlvbi1kZS1sYS12aWUtcHJpdmVlLw==\" target=\"_blank\">charte sur la vie priv\u00e9e<\/span>.<\/div>\n                \n            <\/div>\n        <\/div>\n    <\/div><\/form><\/div><div class=\"multiple_mini hidden\" data-lead_id=\"\"><p class=\"multiple-title\">Merci d&rsquo;avoir pris le temps de remplir ce formulaire<\/p><p>Nous vous contacterons d\u00e8s que possible pour vous orienter vers le meilleur sp\u00e9cialiste correspondant \u00e0 votre demande.<\/p><div class=\"multiple_wrapper\"><div class=\"loader\"><\/div><p class=\"multiple-title\">Vous cherchez d&rsquo;autres services ?<\/p><p class=\"multiple_text\">Vous souhaitez comparer d&rsquo;autres devis ou explorer d&rsquo;autres services ? Faites-le nous savoir et nous vous mettrons rapidement en relation<\/p><div class=\"multiple_container\"><div class=\"single_multiple multiple_button\" data-typeid=\"11428\"><i class=\"fa-3x cat icon-11428\"><\/i><span class=\"multiple_name\">Pompe \u00e0 chaleur<\/span><\/div><div class=\"single_multiple multiple_button\" data-typeid=\"11426\"><i class=\"fa-3x cat icon-11426\"><\/i><span class=\"multiple_name\">Chaudi\u00e8re \u00e0 condensation<\/span><\/div><div class=\"single_multiple multiple_button\" data-typeid=\"30044\"><i class=\"fa-3x cat icon-30044\"><\/i><span class=\"multiple_name\">Chauffe-eau solaire<\/span><\/div><div class=\"single_multiple multiple_button\" data-typeid=\"100131\"><i class=\"fa-3x fad fa-fire\"><\/i><span class=\"multiple_name\">Chaudi\u00e8re \u00e0 pellets, chauffage \u00e0 pellets<\/span><\/div><div class=\"single_multiple multiple_button\" data-typeid=\"11452\"><i class=\"fa-3x fad fa-door-closed\"><\/i><span class=\"multiple_name\">Ch\u00e2ssis, portes et fen\u00eatres<\/span><\/div><div class=\"single_multiple multiple_button\" data-typeid=\"100053\"><i class=\"fa-3x fad fa-battery-bolt\"><\/i><span class=\"multiple_name\">Batterie domestique<\/span><\/div><div class=\"single_multiple hidden multiple_button\" data-typeid=\"100061\"><i class=\"fa-3x fad fa-charging-station\"><\/i><span class=\"multiple_name\">Bornes de recharge<\/span><\/div><div class=\"single_multiple hidden multiple_button\" data-typeid=\"11461\"><i class=\"fa-3x cat icon-11461\"><\/i><span class=\"multiple_name\">Traitement de l&rsquo;humidit\u00e9<\/span><\/div><div class=\"single_multiple hidden multiple_button\" data-typeid=\"11962\"><i class=\"fa-3x cat icon-11962\"><\/i><span class=\"multiple_name\">Travaux de toiture<\/span><\/div><div class=\"single_multiple hidden multiple_button\" data-typeid=\"30002\"><i class=\"fa-3x cat icon-30002\"><\/i><span class=\"multiple_name\">Isolation du toit<\/span><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"featured_media":170698,"parent":47467,"template":"","meta":{"business":"43564","footnotes":""},"class_list":["post-70273","content","type-content","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/content\/70273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/content"}],"about":[{"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/types\/content"}],"version-history":[{"count":9,"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/content\/70273\/revisions"}],"predecessor-version":[{"id":218484,"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/content\/70273\/revisions\/218484"}],"up":[{"embeddable":true,"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/content\/47467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/media\/170698"}],"wp:attachment":[{"href":"https:\/\/www.bobex.be\/fr-be\/wp-json\/wp\/v2\/media?parent=70273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}